{"id":6119,"date":"2025-08-12T02:49:03","date_gmt":"2025-08-12T00:49:03","guid":{"rendered":"https:\/\/afrifoodlinks.org\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/"},"modified":"2025-08-14T03:52:30","modified_gmt":"2025-08-14T01:52:30","slug":"trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux","status":"publish","type":"post","link":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/","title":{"rendered":"Trois fa\u00e7ons dont les jeunes influencent les syst\u00e8mes alimentaires locaux"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6119\" class=\"elementor elementor-6119 elementor-6009\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bdd3500 e-flex e-con-boxed e-con e-parent\" data-id=\"bdd3500\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31b40bb elementor-widget elementor-widget-spacer\" data-id=\"31b40bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52f6c2b e-flex e-con-boxed e-con e-parent\" data-id=\"52f6c2b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1f0da9e e-con-full e-flex e-con e-child\" data-id=\"1f0da9e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d990eb4 elementor-widget elementor-widget-text-editor\" data-id=\"d990eb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La Journ\u00e9e internationale de la jeunesse &#8211; le 12 ao\u00fbt &#8211; est l&rsquo;occasion de r\u00e9fl\u00e9chir \u00e0 la mani\u00e8re dont les jeunes font progresser la coop\u00e9ration multilat\u00e9rale gr\u00e2ce \u00e0 la technologie et aux partenariats. <\/span><i><span style=\"font-weight: 400;\">la coop\u00e9ration multilat\u00e9rale gr\u00e2ce \u00e0 la technologie et aux partenariats<\/span><\/i><span style=\"font-weight: 400;\">. Au sein d&rsquo;AfriFOODlinks, ce th\u00e8me r\u00e9sonne de mani\u00e8re pratique, locale et continue.<\/span><\/p><p><span style=\"font-weight: 400;\">Au cours des 18 derniers mois, 20<\/span><span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/afrifoodlinks.org\/fr\/jeunes-ambassadeurs\/\"><span style=\"font-weight: 400;\"> jeunes ambassadeurs<\/span><\/a><\/span><span style=\"font-weight: 400;\">  ont repr\u00e9sent\u00e9 20 villes d&rsquo;Afrique et d&rsquo;Europe pour AfriFOODlinks. L&rsquo;impact de cette structure va au-del\u00e0 de la g\u00e9ographie : elle cr\u00e9e de v\u00e9ritables opportunit\u00e9s d&rsquo;apprentissage par les pairs, d&rsquo;exp\u00e9rimentation et de r\u00e9flexion commune. Les ambassadeurs se sont engag\u00e9s dans des contextes diff\u00e9rents, partageant des histoires et affrontant parfois m\u00eame des d\u00e9fis similaires sous des angles tr\u00e8s diff\u00e9rents.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc5bb39 e-flex e-con-boxed e-con e-parent\" data-id=\"dc5bb39\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b805d66 elementor-widget elementor-widget-image\" data-id=\"b805d66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/afrifoodlinks.org\/fr\/a-propos-de\/#citiesinvolved\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"531\" src=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/afrifoodlinks-world-map-desktop-2024-1024x531.png\" class=\"attachment-large size-large wp-image-6014\" alt=\"\" srcset=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/afrifoodlinks-world-map-desktop-2024-1024x531.png 1024w, https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/afrifoodlinks-world-map-desktop-2024-300x156.png 300w, https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/afrifoodlinks-world-map-desktop-2024-768x398.png 768w, https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/afrifoodlinks-world-map-desktop-2024-1536x797.png 1536w, https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/afrifoodlinks-world-map-desktop-2024-2048x1062.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Les jeunes ambassadeurs d'AfriFOODlinks repr\u00e9sentent 20 villes d'Afrique et d'Europe, favorisant la collaboration et l'apprentissage partag\u00e9.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-447b58d e-flex e-con-boxed e-con e-parent\" data-id=\"447b58d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-df9d441 elementor-widget elementor-widget-spacer\" data-id=\"df9d441\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f7354c e-flex e-con-boxed e-con e-parent\" data-id=\"2f7354c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a87bc82 elementor-widget elementor-widget-text-editor\" data-id=\"a87bc82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Du Cap (Afrique du Sud) \u00e0 Kisumu (Kenya), et de Tunis (Tunisie) \u00e0 Milan (Italie), les jeunes ambassadeurs ont travaill\u00e9 \u00e0 l&rsquo;intersection de l&rsquo;alimentation, de la communaut\u00e9 et de la communication. Leurs efforts sont all\u00e9s de l&rsquo;organisation d&rsquo;\u00e9v\u00e9nements au niveau de la ville \u00e0 la r\u00e9alisation d&rsquo;interviews dans la rue, en passant par la diffusion de messages de sensibilisation en ligne et m\u00eame la r\u00e9alisation de fresques murales dans leurs villes. Le point commun est un engagement partag\u00e9 \u00e0 rendre les syst\u00e8mes alimentaires locaux plus visibles, plus justes et plus enracin\u00e9s dans les exp\u00e9riences v\u00e9cues.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e56636 e-flex e-con-boxed e-con e-parent\" data-id=\"1e56636\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-04d7872 elementor-widget elementor-widget-spacer\" data-id=\"04d7872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-28e5647 e-flex e-con-boxed e-con e-parent\" data-id=\"28e5647\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de9deec elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"de9deec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpolyline points=&#039;0,18 12,6 24,18 &#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7741d3d e-flex e-con-boxed e-con e-parent\" data-id=\"7741d3d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4045bb0 elementor-widget elementor-widget-spacer\" data-id=\"4045bb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-334814c e-flex e-con-boxed e-con e-parent\" data-id=\"334814c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-07bbe58 elementor-widget elementor-widget-heading\" data-id=\"07bbe58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. Les peintures murales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1bbea3d e-flex e-con-boxed e-con e-parent\" data-id=\"1bbea3d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c76f5b3 elementor-widget elementor-widget-spacer\" data-id=\"c76f5b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b46b737 elementor-widget elementor-widget-text-editor\" data-id=\"b46b737\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Les syst\u00e8mes alimentaires sont le r\u00e9seau complexe de personnes, de lieux et de processus qui fa\u00e7onnent la mani\u00e8re dont nous produisons, partageons et consommons la nourriture, et qui passent souvent inaper\u00e7us dans la vie quotidienne. Gr\u00e2ce aux peintures murales, les jeunes ambassadeurs rendent ces syst\u00e8mes visibles, suscitent des conversations et cr\u00e9ent des liens au sein de leurs communaut\u00e9s. <\/span><\/p><p><span style=\"font-weight: 400;\"><span style=\"color: #00646c;\"><em>\u00ab\u00a0La narration nous donne le pouvoir d&rsquo;interpeller les parties prenantes et les d\u00e9cideurs politiques. Nous pouvons utiliser l&rsquo;art de raconter des histoires pour r\u00e9imaginer notre alimentation\u00a0\u00bb, a d\u00e9clar\u00e9 le jeune ambassadeur Fernando Sozinho (Quelimane, Mozambique). <\/em><\/span>a d\u00e9clar\u00e9 Fernando Sozinho (Quelimane, Mozambique), jeune ambassadeur.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b44504d e-flex e-con-boxed e-con e-parent\" data-id=\"b44504d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9987e35 elementor-widget elementor-widget-gallery\" data-id=\"9987e35\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;columns&quot;:2,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:9,&quot;sizes&quot;:[]},&quot;overlay_title&quot;:&quot;caption&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/7dd18894-304a-48d0-b696-fefdd271631c-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9987e35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjAyOSwidXJsIjoiaHR0cHM6XC9cL2Fmcmlmb29kbGlua3Mub3JnXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvN2RkMTg4OTQtMzA0YS00OGQwLWI2OTYtZmVmZGQyNzE2MzFjLTEuanBnIiwic2xpZGVzaG93IjoiOTk4N2UzNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/7dd18894-304a-48d0-b696-fefdd271631c-1.jpg\" data-width=\"1599\" data-height=\"1323\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tTurin\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/a64fc5fb-61e0-4175-b776-c1de3d0fab9e.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9987e35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjAyNywidXJsIjoiaHR0cHM6XC9cL2Fmcmlmb29kbGlua3Mub3JnXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvYTY0ZmM1ZmItNjFlMC00MTc1LWI3NzYtYzFkZTNkMGZhYjllLmpwZyIsInNsaWRlc2hvdyI6Ijk5ODdlMzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/a64fc5fb-61e0-4175-b776-c1de3d0fab9e.jpg\" data-width=\"1535\" data-height=\"1473\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tMontpellier\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/Copy-of-0d2a20af-e203-4850-a26b-55fef365398a.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9987e35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjAxNSwidXJsIjoiaHR0cHM6XC9cL2Fmcmlmb29kbGlua3Mub3JnXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvQ29weS1vZi0wZDJhMjBhZi1lMjAzLTQ4NTAtYTI2Yi01NWZlZjM2NTM5OGEuanBlZyIsInNsaWRlc2hvdyI6Ijk5ODdlMzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/Copy-of-0d2a20af-e203-4850-a26b-55fef365398a.jpeg\" data-width=\"1000\" data-height=\"750\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tWindhoek\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-06-19-at-19.27.56_500dd894.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9987e35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjAxOSwidXJsIjoiaHR0cHM6XC9cL2Fmcmlmb29kbGlua3Mub3JnXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvV2hhdHNBcHAtSW1hZ2UtMjAyNS0wNi0xOS1hdC0xOS4yNy41Nl81MDBkZDg5NC5qcGciLCJzbGlkZXNob3ciOiI5OTg3ZTM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-06-19-at-19.27.56_500dd894.jpg\" data-width=\"2560\" data-height=\"1706\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tNaimey\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-06-19-at-19.27.56_d72b8cf5.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9987e35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjAyMSwidXJsIjoiaHR0cHM6XC9cL2Fmcmlmb29kbGlua3Mub3JnXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvV2hhdHNBcHAtSW1hZ2UtMjAyNS0wNi0xOS1hdC0xOS4yNy41Nl9kNzJiOGNmNS5qcGciLCJzbGlkZXNob3ciOiI5OTg3ZTM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-06-19-at-19.27.56_d72b8cf5.jpg\" data-width=\"2560\" data-height=\"1437\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tNaimey\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/PHOTO-2025-07-28-11-36-07.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9987e35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjAyMywidXJsIjoiaHR0cHM6XC9cL2Fmcmlmb29kbGlua3Mub3JnXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvUEhPVE8tMjAyNS0wNy0yOC0xMS0zNi0wNy5qcGciLCJzbGlkZXNob3ciOiI5OTg3ZTM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/PHOTO-2025-07-28-11-36-07.jpg\" data-width=\"960\" data-height=\"1280\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tKisumu\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-05-16-at-13.26.53_3f258f0b.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9987e35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjAyNSwidXJsIjoiaHR0cHM6XC9cL2Fmcmlmb29kbGlua3Mub3JnXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvV2hhdHNBcHAtSW1hZ2UtMjAyNS0wNS0xNi1hdC0xMy4yNi41M18zZjI1OGYwYi5qcGciLCJzbGlkZXNob3ciOiI5OTg3ZTM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-05-16-at-13.26.53_3f258f0b.jpg\" data-width=\"1200\" data-height=\"1600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tAntananarivo\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-05-16-at-13.26.53_5d7a9207.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9987e35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjAxNywidXJsIjoiaHR0cHM6XC9cL2Fmcmlmb29kbGlua3Mub3JnXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvV2hhdHNBcHAtSW1hZ2UtMjAyNS0wNS0xNi1hdC0xMy4yNi41M181ZDdhOTIwNy5qcGciLCJzbGlkZXNob3ciOiI5OTg3ZTM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-05-16-at-13.26.53_5d7a9207.jpg\" data-width=\"1600\" data-height=\"1200\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tAntananarivo\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-821fc81 elementor-widget elementor-widget-spacer\" data-id=\"821fc81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96595b5 e-flex e-con-boxed e-con e-parent\" data-id=\"96595b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-263eb6f elementor-widget elementor-widget-text-editor\" data-id=\"263eb6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Par ordre d&rsquo;apparition :  <\/span><\/p><ol><li style=\"font-weight: 400;\" aria-level=\"1\"><p><strong><span style=\"color: #00646c;\">Turin, Italie<\/span><\/strong><span>&#8211;<span style=\"color: #00646c;\">R\u00e9imaginer<\/span> notre place dans l&rsquo;\u00e9cosyst\u00e8me &#8211; Un appel \u00e0 l&rsquo;harmonie entre les personnes, la nourriture, l&rsquo;eau et la nature. <\/span><i><span>Par Francesca Allemano et Shad\u00e9.<\/span><\/i><\/p><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><p><i><\/i><span style=\"color: #00646c;\"><b>Montpellier, France<\/b><\/span><span style=\"font-weight: 400;\"> &#8211; Nos produits, notre r\u00e9gion &#8211; Pr\u00e9sentation de 10 aliments embl\u00e9matiques li\u00e9s aux paysages et aux traditions de Montpellier. <\/span><i><span style=\"font-weight: 400;\">Par Doriane Ouedraogo et Lou Bernard.<\/span><\/i><\/p><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><p><i><\/i><span style=\"color: #00646c;\"><strong>Windhoek, Namibie &#8211;<\/strong><\/span> From the Ground Up &#8211; C\u00e9l\u00e9bration de la ferme Okukuna et de la vision d&rsquo;une ville plus verte, dirig\u00e9e par des jeunes et jouissant d&rsquo;une s\u00e9curit\u00e9 alimentaire. Par Kaylah Cordom et Frans Nambinga. <\/p><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #00646c;\"><b>Niamey, Niger<\/b><\/span><span style=\"font-weight: 400;\"> &#8211;<span style=\"color: #00646c;\"> Rien de<\/span> gaspill\u00e9 &#8211; Inspirer le compostage et le tri des d\u00e9chets avec des messages tels que \u00ab\u00a0Chaque grain de mil compte\u00a0\u00bb.<\/span><i><span style=\"font-weight: 400;\"> Par Mariama Chitou et \u00c9ric Sovuthy Kruoch<\/span><\/i><\/li><li aria-level=\"1\"> <\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #00646c;\"><b>Kisumu, Kenya<\/b><\/span><span style=\"font-weight: 400;\"> &#8211; Don du<span style=\"color: #00646c;\"> lac<\/span>: La sant\u00e9 de la ville &#8211; Lier la g\u00e9n\u00e9rosit\u00e9 du lac Victoria \u00e0 la sant\u00e9 de la communaut\u00e9 et aux r\u00e9gimes alimentaires durables. <\/span><i><span style=\"font-weight: 400;\">Par Bonareri Morara et Daniel Malik.<\/span><\/i><\/li><li aria-level=\"1\"> <\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #00646c;\"><b>Antananarivo, Madagascar<\/b><\/span><span style=\"font-weight: 400;\"> &#8211;<span style=\"color: #00646c;\"> Des<\/span> d\u00e9chets \u00e0 l&rsquo;\u00e9merveillement &#8211; Transformer des mat\u00e9riaux recycl\u00e9s en \u0153uvres d&rsquo;art sur la pollution, le compostage et la nourriture locale. <\/span><i><span style=\"font-weight: 400;\">Par Tiakaly, Dina Mitia Rabearivelo et Radisson Tamboho.<\/span><\/i><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d59d97 elementor-widget elementor-widget-text-editor\" data-id=\"1d59d97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Gr\u00e2ce \u00e0 ces peintures murales, les jeunes nous rappellent que le changement le plus puissant commence souvent par l&rsquo;imagination et la mise en \u0153uvre de syst\u00e8mes alimentaires plus sains et plus justes.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-767f746 e-flex e-con-boxed e-con e-parent\" data-id=\"767f746\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1325839 elementor-widget elementor-widget-spacer\" data-id=\"1325839\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-93981d7 e-flex e-con-boxed e-con e-parent\" data-id=\"93981d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2a5ec6 elementor-widget elementor-widget-heading\" data-id=\"c2a5ec6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2. Technologie et partenariats\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-387093a e-flex e-con-boxed e-con e-parent\" data-id=\"387093a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a0cc4b elementor-widget elementor-widget-spacer\" data-id=\"6a0cc4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4c79bc elementor-widget elementor-widget-text-editor\" data-id=\"c4c79bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Les outils num\u00e9riques sont essentiels pour permettre aux ambassadeurs d&rsquo;atteindre diff\u00e9rents publics et d&rsquo;\u00e9changer des id\u00e9es. Certains utilisent les m\u00e9dias sociaux pour mettre en avant les cultures alimentaires locales ou sensibiliser \u00e0 l&rsquo;acc\u00e8s et \u00e0 l&rsquo;accessibilit\u00e9 financi\u00e8re. D&rsquo;autres s&rsquo;appuient sur des photos et des vid\u00e9os, des groupes de discussion et des \u00e9v\u00e9nements virtuels. Le fil conducteur est l&rsquo;utilisation de la technologie comme outil d&rsquo;inclusion.   <\/span><\/p><p><span style=\"font-weight: 400;\"><em><span style=\"color: #00646c;\">\u00ab\u00a0Nous devons faire preuve de cr\u00e9ativit\u00e9 pour susciter l&rsquo;int\u00e9r\u00eat des jeunes\u00a0\u00bb, a d\u00e9clar\u00e9 l&rsquo;ambassadeur de la jeunesse Tegitu Casiraghi (Milan, Italie).<\/span><\/em> a d\u00e9clar\u00e9 Tegitu Casiraghi (Milan, Italie), ambassadeur de la jeunesse.<\/span><\/p><p><span style=\"font-weight: 400;\">Par exemple, un <\/span><span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/youtu.be\/iGI1i5ds_HU\"><span style=\"font-weight: 400;\">webinaire anim\u00e9 par des jeunes<\/span><\/a><\/span><span style=\"font-weight: 400;\">  qui s&rsquo;est tenue en juillet 2025, a d\u00e9montr\u00e9 comment la technologie peut favoriser une collaboration significative et inclusive. Les jeunes ambassadeurs d&rsquo;AfriFOODlinks ont assur\u00e9 la facilitation, le soutien technique, le contenu et l&rsquo;interpr\u00e9tation simultan\u00e9e fran\u00e7ais-anglais pour un dialogue en temps r\u00e9el.   <\/span><\/p><p><span style=\"font-weight: 400;\">\u00c0 Arusha, l&rsquo;ambassadeur Filbert Minja a pr\u00e9sent\u00e9 la plateforme dirig\u00e9e par des jeunes <\/span><span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/youtu.be\/UuVwTij-Qsc\"><span style=\"font-weight: 400;\">Sambazah<\/span><\/a><\/span><span style=\"font-weight: 400;\">qui met en relation les vendeurs de produits alimentaires et les consommateurs afin de soutenir les cha\u00eenes d&rsquo;approvisionnement locales.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-131f9e3 e-flex e-con-boxed e-con e-parent\" data-id=\"131f9e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-097e7c3 elementor-widget elementor-widget-spacer\" data-id=\"097e7c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b4d089b e-flex e-con-boxed e-con e-parent\" data-id=\"b4d089b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e0fb6f2 e-con-full e-flex e-con e-child\" data-id=\"e0fb6f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c9a92f elementor-widget elementor-widget-heading\" data-id=\"5c9a92f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3. La coop\u00e9ration \u00e0 partir de la base<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c937d2 e-flex e-con-boxed e-con e-parent\" data-id=\"2c937d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2227c6a e-con-full e-flex e-con e-child\" data-id=\"2227c6a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5195dca elementor-widget elementor-widget-spacer\" data-id=\"5195dca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dad1b74 elementor-widget elementor-widget-text-editor\" data-id=\"dad1b74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Le programme AfriFOODlinks Youth Ambassadorship a toujours \u00e9t\u00e9 ax\u00e9 sur l&rsquo;exp\u00e9rimentation, la connexion et l&rsquo;adaptation des id\u00e9es au contexte. Bien que les ambassadeurs aient travaill\u00e9 de mani\u00e8re ind\u00e9pendante dans leurs villes respectives, nombre d&rsquo;entre eux ont trouv\u00e9 des points communs dans les questions qu&rsquo;ils posaient. Beaucoup ont partag\u00e9 des id\u00e9es ou se sont appuy\u00e9s sur le travail des autres. Certains ont collabor\u00e9 directement. Et pour d&rsquo;autres, le simple fait de voir ce qui se passait dans une autre partie du continent, ou du monde, a modifi\u00e9 leur fa\u00e7on de penser leur propre travail.    <\/span><\/p><p><span style=\"font-weight: 400;\"><em><span style=\"color: #00646c;\">\u00ab\u00a0Parce que nous sommes de jeunes ambassadeurs, nous avons un si\u00e8ge \u00e0 la table\u00a0\u00bb, a d\u00e9clar\u00e9 Kaylah Cordom (Windhoek, Namibie), jeune ambassadrice.<\/span><\/em> a d\u00e9clar\u00e9 Kaylah Cordom (Windhoek, Namibie).<\/span><\/p><p><span style=\"font-weight: 400;\">\u00c0 Kisumu, l&rsquo;ambassadeur Bonareri Morara a abord\u00e9 les questions suivantes <\/span><span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/youtu.be\/VprU5wOb-88\"><span style=\"font-weight: 400;\">les pertes de poissons apr\u00e8s r\u00e9colte et l&rsquo;exclusion des femmes<\/span><\/a><\/span><span style=\"font-weight: 400;\">  dans la cha\u00eene de valeur. Apr\u00e8s avoir d\u00e9couvert la technologie du s\u00e9chage solaire gr\u00e2ce aux connexions d&rsquo;AfriFOODlinks et \u00e0 sa participation au programme d&rsquo;incubation d&rsquo;entreprises du projet, elle l&rsquo;a pr\u00e9sent\u00e9e aux vendeuses de poisson locales. Elle les a impliqu\u00e9es directement dans la prise de d\u00e9cision, favorisant ainsi l&rsquo;appropriation et l&rsquo;adoption de la nouvelle m\u00e9thode.  <\/span><\/p><p><span style=\"font-weight: 400;\">\u00c0 Mbale, l&rsquo;ambassadeur Sam Wesamoyo s&rsquo;est associ\u00e9 \u00e0 des organisations locales et \u00e0 des universitaires pour mener une campagne d&rsquo;activation \u00e0 l&rsquo;\u00e9chelle de la ville. <\/span><span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/www.linkedin.com\/posts\/sam-wesamoyo-19570815a_afrifoodlinks-throughfood-food2030eu-activity-7201130145967955969-RNps?utm_source=share&amp;utm_medium=member_desktop&amp;rcm=ACoAACYxKwEB8zGddPpe7LSFVoFe19lzrQ3AvCE\"><span style=\"font-weight: 400;\">d&rsquo;activation<\/span><\/a><\/span><span style=\"font-weight: 400;\">  sur le th\u00e8me de la s\u00e9curit\u00e9 alimentaire au march\u00e9 de Namakwekwe. Combinant nettoyage, engagement des vendeurs et formation \u00e0 l&rsquo;hygi\u00e8ne, l&rsquo;\u00e9v\u00e9nement s&rsquo;est attaqu\u00e9 \u00e0 des probl\u00e8mes de longue date tels que l&rsquo;obstruction des \u00e9gouts et la mauvaise manipulation des aliments. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed433bd e-flex e-con-boxed e-con e-parent\" data-id=\"ed433bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47fcd59 elementor-widget elementor-widget-spacer\" data-id=\"47fcd59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c86b36 e-flex e-con-boxed e-con e-parent\" data-id=\"4c86b36\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-61207fc e-con-full e-flex e-con e-child\" data-id=\"61207fc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9c658c6 e-con-full e-flex e-con e-child\" data-id=\"9c658c6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4ed5c5 elementor-widget elementor-widget-heading\" data-id=\"d4ed5c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quelle est la prochaine \u00e9tape ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5690663 e-flex e-con-boxed e-con e-parent\" data-id=\"5690663\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-80be533 e-con-full e-flex e-con e-child\" data-id=\"80be533\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7b8d2f6 e-con-full e-flex e-con e-child\" data-id=\"7b8d2f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7377311 elementor-widget elementor-widget-spacer\" data-id=\"7377311\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bad348 elementor-widget elementor-widget-text-editor\" data-id=\"4bad348\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Il n&rsquo;existe pas de mod\u00e8le unique pour le leadership des jeunes dans les syst\u00e8mes alimentaires. Gr\u00e2ce au r\u00f4le d&rsquo;ambassadeur de la jeunesse, AfriFOODlinks a cr\u00e9\u00e9 un espace pour une action locale pertinente men\u00e9e par les jeunes, tout en reconnaissant sa valeur en tant que contribution \u00e0 la politique et en tant que moteur de changement sur le terrain. Ces jeunes ambassadeurs se sont attaqu\u00e9s \u00e0 des probl\u00e8mes allant de l&rsquo;acc\u00e8s \u00e0 la nourriture et des d\u00e9chets au commerce de rue et \u00e0 l&rsquo;exclusion des femmes de la vie \u00e9conomique et politique. Mais leur travail n&rsquo;est pas fig\u00e9 ; il continue d&rsquo;\u00e9voluer, avec des peintures murales, des \u00e9v\u00e9nements urbains et des histoires. Nombre d&rsquo;entre eux imaginent d\u00e9j\u00e0 ce que pourrait \u00eatre la participation des jeunes dans leur ville dans les ann\u00e9es \u00e0 venir, au-del\u00e0 d&rsquo;AfriFOODlinks.    <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef6e6c6 elementor-widget elementor-widget-spacer\" data-id=\"ef6e6c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b1bc4d8 e-flex e-con-boxed e-con e-parent\" data-id=\"b1bc4d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b59d08 elementor-widget elementor-widget-spacer\" data-id=\"8b59d08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fc11cf e-flex e-con-boxed e-con e-parent\" data-id=\"4fc11cf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;split&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 20\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,0v3c0,0,393.8,0,483.4,0c9.2,0,16.6,7.4,16.6,16.6c0-9.1,7.4-16.6,16.6-16.6C606.2,3,1000,3,1000,3V0H0z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22fa40f e-con-full e-flex e-con e-child\" data-id=\"22fa40f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc2a41c elementor-widget elementor-widget-spacer\" data-id=\"dc2a41c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b03140 elementor-widget elementor-widget-text-editor\" data-id=\"9b03140\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><i><span style=\"font-weight: 400;\">Explorez la page <\/span><\/i><a href=\"https:\/\/afrifoodlinks.org\/fr\/?page_id=4992\"><i><span style=\"font-weight: 400;\">Histoires de jeunes ambassadeurs<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> pour voir ce qui a d\u00e9j\u00e0 \u00e9t\u00e9 fait.<\/span><\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ef7a80 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3ef7a80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/afrifoodlinks.org\/fr\/?page_id=4992\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cliquez ici pour d\u00e9couvrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4155185 e-con-full e-flex e-con e-child\" data-id=\"4155185\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03a8692 elementor-widget elementor-widget-spacer\" data-id=\"03a8692\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40fae6a elementor-widget elementor-widget-text-editor\" data-id=\"40fae6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><i><span style=\"font-weight: 400;\">Regardez la vid\u00e9o des jeunes ambassadeurs d&rsquo;AfriFOODlinks <\/span><\/i><a href=\"https:\/\/youtu.be\/-5llAv7g-Mw\"><i><span style=\"font-weight: 400;\">vid\u00e9o des jeunes ambassadeurs d&rsquo;AfriFOODlinks<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> pour entendre directement les ambassadeurs.<\/span><\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4971a6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d4971a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/afrifoodlinks.org\/fr\/resource\/transformation-audacieuse-des-systemes-alimentaires-urbains-sous-limpulsion-des-jeunes\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cliquez ici pour regarder<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96c2ec7 elementor-widget elementor-widget-spacer\" data-id=\"96c2ec7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Journ\u00e9e internationale de la jeunesse (12 ao\u00fbt) est l&rsquo;occasion de r\u00e9fl\u00e9chir \u00e0 la mani\u00e8re dont les jeunes font progresser la coop\u00e9ration multilat\u00e9rale gr\u00e2ce \u00e0 l&rsquo;innovation, aux partenariats et aux solutions pratiques.<\/p>\n","protected":false},"author":3,"featured_media":6011,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1629,1632,1633,1634],"tags":[1600,1635,1636,1637],"class_list":["post-6119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-collaboration-ue-ua","category-droits-de-lhomme-et-droits-des-femmes","category-jeunes-ambassadeurs","category-marches","tag-resilience-alimentaire","tag-defense-des-interets-des-jeunes","tag-systemes-alimentaires-locaux","tag-des-systemes-alimentaires-justes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trois fa\u00e7ons dont les jeunes influencent les syst\u00e8mes alimentaires locaux - afrifoodlinks<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trois fa\u00e7ons dont les jeunes influencent les syst\u00e8mes alimentaires locaux - afrifoodlinks\" \/>\n<meta property=\"og:description\" content=\"La Journ\u00e9e internationale de la jeunesse (12 ao\u00fbt) est l&#039;occasion de r\u00e9fl\u00e9chir \u00e0 la mani\u00e8re dont les jeunes font progresser la coop\u00e9ration multilat\u00e9rale gr\u00e2ce \u00e0 l&#039;innovation, aux partenariats et aux solutions pratiques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/\" \/>\n<meta property=\"og:site_name\" content=\"afrifoodlinks\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-12T00:49:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-14T01:52:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2024-11-26-at-08.31.36_bb6f633e.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"afladmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"afladmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\\\/\"},\"author\":{\"name\":\"afladmin\",\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/#\\\/schema\\\/person\\\/0d13099a22c5d27bcd1caa39a9318f26\"},\"headline\":\"Trois fa\u00e7ons dont les jeunes influencent les syst\u00e8mes alimentaires locaux\",\"datePublished\":\"2025-08-12T00:49:03+00:00\",\"dateModified\":\"2025-08-14T01:52:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\\\/\"},\"wordCount\":1373,\"publisher\":{\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/afrifoodlinks.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WhatsApp-Image-2024-11-26-at-08.31.36_bb6f633e.jpg\",\"keywords\":[\"r\u00e9silience alimentaire\",\"D\u00e9fense des int\u00e9r\u00eats des jeunes\",\"syst\u00e8mes alimentaires locaux\",\"Des syst\u00e8mes alimentaires justes\"],\"articleSection\":[\"Collaboration UE-UA\",\"Droits de l'homme et droits des femmes\",\"Jeunes ambassadeurs\",\"March\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\\\/\",\"url\":\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\\\/\",\"name\":\"Trois fa\u00e7ons dont les jeunes influencent les syst\u00e8mes alimentaires locaux - afrifoodlinks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/afrifoodlinks.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WhatsApp-Image-2024-11-26-at-08.31.36_bb6f633e.jpg\",\"datePublished\":\"2025-08-12T00:49:03+00:00\",\"dateModified\":\"2025-08-14T01:52:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/afrifoodlinks.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WhatsApp-Image-2024-11-26-at-08.31.36_bb6f633e.jpg\",\"contentUrl\":\"https:\\\/\\\/afrifoodlinks.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WhatsApp-Image-2024-11-26-at-08.31.36_bb6f633e.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trois fa\u00e7ons dont les jeunes influencent les syst\u00e8mes alimentaires locaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/#website\",\"url\":\"https:\\\/\\\/afrifoodlinks.org\\\/\",\"name\":\"afrifoodlinks\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/afrifoodlinks.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/#organization\",\"name\":\"afrifoodlinks\",\"url\":\"https:\\\/\\\/afrifoodlinks.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/afrifoodlinks.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/afrifoodlinks-logo-seo.png\",\"contentUrl\":\"https:\\\/\\\/afrifoodlinks.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/afrifoodlinks-logo-seo.png\",\"width\":420,\"height\":178,\"caption\":\"afrifoodlinks\"},\"image\":{\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/explore\\\/tags\\\/throughfood\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/afrifoodlinks.org\\\/#\\\/schema\\\/person\\\/0d13099a22c5d27bcd1caa39a9318f26\",\"name\":\"afladmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ea049ed540330c08c1bcf62d201c0374b129bed886883a6d3aa1e5527322fad?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ea049ed540330c08c1bcf62d201c0374b129bed886883a6d3aa1e5527322fad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ea049ed540330c08c1bcf62d201c0374b129bed886883a6d3aa1e5527322fad?s=96&d=mm&r=g\",\"caption\":\"afladmin\"},\"url\":\"https:\\\/\\\/afrifoodlinks.org\\\/fr\\\/author\\\/afladmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trois fa\u00e7ons dont les jeunes influencent les syst\u00e8mes alimentaires locaux - afrifoodlinks","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Trois fa\u00e7ons dont les jeunes influencent les syst\u00e8mes alimentaires locaux - afrifoodlinks","og_description":"La Journ\u00e9e internationale de la jeunesse (12 ao\u00fbt) est l'occasion de r\u00e9fl\u00e9chir \u00e0 la mani\u00e8re dont les jeunes font progresser la coop\u00e9ration multilat\u00e9rale gr\u00e2ce \u00e0 l'innovation, aux partenariats et aux solutions pratiques.","og_url":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/","og_site_name":"afrifoodlinks","article_published_time":"2025-08-12T00:49:03+00:00","article_modified_time":"2025-08-14T01:52:30+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2024-11-26-at-08.31.36_bb6f633e.jpg","type":"image\/jpeg"}],"author":"afladmin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"afladmin","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/#article","isPartOf":{"@id":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/"},"author":{"name":"afladmin","@id":"https:\/\/afrifoodlinks.org\/#\/schema\/person\/0d13099a22c5d27bcd1caa39a9318f26"},"headline":"Trois fa\u00e7ons dont les jeunes influencent les syst\u00e8mes alimentaires locaux","datePublished":"2025-08-12T00:49:03+00:00","dateModified":"2025-08-14T01:52:30+00:00","mainEntityOfPage":{"@id":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/"},"wordCount":1373,"publisher":{"@id":"https:\/\/afrifoodlinks.org\/#organization"},"image":{"@id":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/#primaryimage"},"thumbnailUrl":"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2024-11-26-at-08.31.36_bb6f633e.jpg","keywords":["r\u00e9silience alimentaire","D\u00e9fense des int\u00e9r\u00eats des jeunes","syst\u00e8mes alimentaires locaux","Des syst\u00e8mes alimentaires justes"],"articleSection":["Collaboration UE-UA","Droits de l'homme et droits des femmes","Jeunes ambassadeurs","March\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/","url":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/","name":"Trois fa\u00e7ons dont les jeunes influencent les syst\u00e8mes alimentaires locaux - afrifoodlinks","isPartOf":{"@id":"https:\/\/afrifoodlinks.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/#primaryimage"},"image":{"@id":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/#primaryimage"},"thumbnailUrl":"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2024-11-26-at-08.31.36_bb6f633e.jpg","datePublished":"2025-08-12T00:49:03+00:00","dateModified":"2025-08-14T01:52:30+00:00","breadcrumb":{"@id":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/#primaryimage","url":"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2024-11-26-at-08.31.36_bb6f633e.jpg","contentUrl":"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2024-11-26-at-08.31.36_bb6f633e.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/afrifoodlinks.org\/fr\/trois-facons-dont-les-jeunes-influencent-les-systemes-alimentaires-locaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/afrifoodlinks.org\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Trois fa\u00e7ons dont les jeunes influencent les syst\u00e8mes alimentaires locaux"}]},{"@type":"WebSite","@id":"https:\/\/afrifoodlinks.org\/#website","url":"https:\/\/afrifoodlinks.org\/","name":"afrifoodlinks","description":"","publisher":{"@id":"https:\/\/afrifoodlinks.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/afrifoodlinks.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/afrifoodlinks.org\/#organization","name":"afrifoodlinks","url":"https:\/\/afrifoodlinks.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/afrifoodlinks.org\/#\/schema\/logo\/image\/","url":"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2023\/05\/afrifoodlinks-logo-seo.png","contentUrl":"https:\/\/afrifoodlinks.org\/wp-content\/uploads\/2023\/05\/afrifoodlinks-logo-seo.png","width":420,"height":178,"caption":"afrifoodlinks"},"image":{"@id":"https:\/\/afrifoodlinks.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/explore\/tags\/throughfood\/"]},{"@type":"Person","@id":"https:\/\/afrifoodlinks.org\/#\/schema\/person\/0d13099a22c5d27bcd1caa39a9318f26","name":"afladmin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8ea049ed540330c08c1bcf62d201c0374b129bed886883a6d3aa1e5527322fad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ea049ed540330c08c1bcf62d201c0374b129bed886883a6d3aa1e5527322fad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ea049ed540330c08c1bcf62d201c0374b129bed886883a6d3aa1e5527322fad?s=96&d=mm&r=g","caption":"afladmin"},"url":"https:\/\/afrifoodlinks.org\/fr\/author\/afladmin\/"}]}},"_links":{"self":[{"href":"https:\/\/afrifoodlinks.org\/fr\/wp-json\/wp\/v2\/posts\/6119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afrifoodlinks.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afrifoodlinks.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afrifoodlinks.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/afrifoodlinks.org\/fr\/wp-json\/wp\/v2\/comments?post=6119"}],"version-history":[{"count":1,"href":"https:\/\/afrifoodlinks.org\/fr\/wp-json\/wp\/v2\/posts\/6119\/revisions"}],"predecessor-version":[{"id":6120,"href":"https:\/\/afrifoodlinks.org\/fr\/wp-json\/wp\/v2\/posts\/6119\/revisions\/6120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/afrifoodlinks.org\/fr\/wp-json\/wp\/v2\/media\/6011"}],"wp:attachment":[{"href":"https:\/\/afrifoodlinks.org\/fr\/wp-json\/wp\/v2\/media?parent=6119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afrifoodlinks.org\/fr\/wp-json\/wp\/v2\/categories?post=6119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afrifoodlinks.org\/fr\/wp-json\/wp\/v2\/tags?post=6119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}